{"id":1883,"date":"2022-03-22T17:50:49","date_gmt":"2022-03-22T17:50:49","guid":{"rendered":"http:\/\/oshoclinicpanchkula.com\/\/?page_id=1883"},"modified":"2022-03-28T05:43:27","modified_gmt":"2022-03-28T05:43:27","slug":"yale-brown-obsessive-compulsive-scale","status":"publish","type":"page","link":"https:\/\/oshoclinicpanchkula.com\/index.php\/yale-brown-obsessive-compulsive-scale\/","title":{"rendered":"Yale-Brown Obsessive Compulsive Scale"},"content":{"rendered":"<p>[vc_section][vc_row][vc_column][vc_column_text]<\/p>\n<h5><strong>Note:\u00a0<\/strong><\/h5>\n<p>Scores should reflect the composite effect of all the patient\u2019s obsessive-compulsive symptoms. Rate the average occurrence of each item during the prior week up to and including the time of interview:<\/p>\n<p><em><strong>Question 1-5: Obsession Rating Scale(Circle Appropriate Score)<\/strong><\/em><br \/>\n<em><strong>Question 6-10: Compulsion Rating Scale(Circle Appropriate Score)<\/strong><\/em>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1648446185880{padding-top: 30px !important;}&#8221;][vc_row][vc_column][vc_column_text]<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-2296\"><form id=\"wpforms-form-2296\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2296\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/1883\" data-token=\"5d81eb8e1f959de7e1458a78c41922bd\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2296-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_1\">Full Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-2296-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-2296-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_2\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2296-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-2296-field_3-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_3\">Time Spent on Obsessions: 0hr\/day(Score=0), 0-1hr\/day(Score=1), 1-3hr\/day(Score=2), 3-8hr\/day(Score=3), &gt;8hr\/day(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_11-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"11\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_11\"> Interference From Obessions: None(Score=0), Mild(Score=1), Definite but manageable(Score=2), Substantial Impairment(Score=3), Incapacitating(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_11\" class=\"wpforms-field-medium\" name=\"wpforms[fields][11]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_13-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"13\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_13\"> Distress From Obsessions: None(Score=0), Little(Score=1), Moderate but manageable(Score=2), Severe(Score=3), Near constant disabling(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_13\" class=\"wpforms-field-medium\" name=\"wpforms[fields][13]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_10-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_10\">Resistance to Obsessions: Always resists(Score=0), Much resistance(Score=1), Some resistance(Score=2), often yields(Score=3), Completely yields(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_10\" class=\"wpforms-field-medium\" name=\"wpforms[fields][10]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_9-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"9\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_9\">Control Over Obsessions: Complete control(Score=0), Much control(Score=1), Some control(Score=2), Little control(Score=3), No control(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_9\" class=\"wpforms-field-medium\" name=\"wpforms[fields][9]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_8-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_8\">Time Spent on Compulsion : 0hr\/day(Score=0), 0-1hr\/day(Score=1), 1-3hr\/day(Score=2), 3-8hr\/day(Score=3), &gt;8hr\/day(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_8\" class=\"wpforms-field-medium\" name=\"wpforms[fields][8]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_7-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_7\">Interference From Compulsion: None(Score=0), Mild(Score=1), Definite but manageable(Score=2), Substantial Impairment(Score=3), Incapacitating(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_6-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_6\">Distress From Compulsion: None(Score=0), Little(Score=1), Moderate but manageable(Score=2), Severe(Score=3), Near constant disabling(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_5-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_5\">Resistance to Compulsion: Always resists(Score=0), Much resistance(Score=1), Some resistance(Score=2), often yields(Score=3), Completely yields(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><div id=\"wpforms-2296-field_4-container\" class=\"wpforms-field wpforms-field-number-slider\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2296-field_4\">Control Over Compulsion: Complete control(Score=0), Much control(Score=1), Some control(Score=2), Little control(Score=3), No control(Score=4)<\/label>\n<input\n\ttype=\"range\"\n\tid=\"wpforms-2296-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" value=\"0\"\t\tvalue=\"0\"\n\tmin=\"0\"\n\tmax=\"4\"\n\tstep=\"1\">\n\n<div class=\"wpforms-field-number-slider-hint\"\n\tdata-hint=\"Selected Value: {value}\">\n\tSelected Value: <b>0<\/b><\/div>\n<div class=\"wpforms-field-description\">For Example Score is: 4<\/div><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"2296\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2296\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/oshoclinicpanchkula.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_section][vc_row][vc_column][vc_column_text] Note:\u00a0 Scores should reflect the composite effect of all the patient\u2019s obsessive-compulsive symptoms. Rate the average occurrence of each item during the prior week up to and including the time of interview: Question 1-5: Obsession Rating Scale(Circle Appropriate Score) Question 6-10: Compulsion Rating Scale(Circle Appropriate Score)[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section css=&#8221;.vc_custom_1648446185880{padding-top: 30px !important;}&#8221;][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][\/vc_section]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1883","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/pages\/1883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/comments?post=1883"}],"version-history":[{"count":4,"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/pages\/1883\/revisions"}],"predecessor-version":[{"id":2300,"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/pages\/1883\/revisions\/2300"}],"wp:attachment":[{"href":"https:\/\/oshoclinicpanchkula.com\/index.php\/wp-json\/wp\/v2\/media?parent=1883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}